{"id":10553,"date":"2022-06-08T17:24:32","date_gmt":"2022-06-08T15:24:32","guid":{"rendered":"https:\/\/www.plantcaretools.com\/planten-water-geven-faq\/"},"modified":"2026-04-02T13:14:50","modified_gmt":"2026-04-02T11:14:50","slug":"arroser-les-plantes-faq","status":"publish","type":"page","link":"https:\/\/www.plantcaretools.com\/fr\/arroser-les-plantes-faq\/","title":{"rendered":"Arroser les Plantes FAQ"},"content":{"rendered":"<div class=\"gb-container gb-container-4ef4fffb alignfull\"><div class=\"gb-inside-container\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-a9c28f01\">\n<div class=\"gb-grid-column gb-grid-column-f4ce2e6f\"><div class=\"gb-container gb-container-f4ce2e6f\"><div class=\"gb-inside-container\">\n\n<h1 class=\"wp-block-heading has-text-align-center has-palette-color-8-color has-text-color\" id=\"h-arroser-les-plantes-faq\">Arroser les Plantes FAQ<\/h1>\n\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-9bd7f1c0 bg-gradient-vertical  alignfull\"><div class=\"gb-inside-container\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-27524df7\">\n<div class=\"gb-grid-column gb-grid-column-c7d87555\"><div class=\"gb-container gb-container-c7d87555\"><div class=\"gb-inside-container\">\n<span><span><a href=\"https:\/\/www.plantcaretools.com\/fr\/\">Home<\/a><\/span><\/span>\n\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-55e5c7c9\"><div class=\"gb-inside-container\">\n\n<h2 class=\"wp-block-heading\" id=\"h-arroser-les-plantes-faq-mesurez-l-humidite-du-sol-pour-un-entretien-approprie\"><strong>Arroser les plantes FAQ: mesurez l\u2019humidit\u00e9 du sol pour un entretien appropri\u00e9<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vous trouverez ici une liste de questions fr\u00e9quemment (FAQ) pos\u00e9es sur l\u2019arrosage des plantes \u2013 \u00e0 l\u2019int\u00e9rieur, en conteneurs ou autres plantes en pot. Mais aussi des informations sur l\u2019entretien de la pelouse et des plantes dans la cour ou le potager.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Plantes d\u2019int\u00e9rieur et arrosage: foire aux questions sur l\u2019arrosage des plantes<\/strong><\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer mobile-25\"><\/div>\n\n\n<div class=\"gb-grid-wrapper gb-grid-wrapper-f1e0da90\">\n<div class=\"gb-grid-column gb-grid-column-80866ca5\"><div class=\"gb-container gb-container-80866ca5\"><div class=\"gb-inside-container\">\n<section class=\"alignfull\">\r\n            <ul class=\"accordion-section\">\r\n                            <li class=\"accordion-row\">\r\n                    <a class=\"toggle\" href=#>\r\n                                                                            <h4 class=\"accordion-title\">Combien d\u2019eau dois-je donner \u00e0 mes plantes d\u2019int\u00e9rieur?<\/h4>\r\n                                                <div class=\"switcher-icon\">\r\n                                                            <img decoding=\"async\" class=\"open-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/minus-regular.svg\" alt=\"\"\/>\r\n                                                                                        <img decoding=\"async\" class=\"close-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/plus-regular.svg\" alt=\"\"\/>\r\n                                                    <\/div>\r\n                    <\/a>\r\n                    <div class=\"inner\">\r\n                                                                            <div><p>Il n\u2019existe pas de r\u00e8gle g\u00e9n\u00e9rale pour l\u2019arrosage des plantes car chaque plante est unique: une plante \u00e0 grandes feuilles provient d\u2019une for\u00eat tropicale humide, l\u2019autre vient d\u2019une r\u00e9gion de haute montagne o\u00f9 il pleut toujours, ou d\u2019un d\u00e9sert o\u00f9 c\u2019est toujours sec, par exemple. Chaque plante a donc ses propres besoins en eau.<br \/>\nCependant, la teneur en humidit\u00e9 ou le niveau d\u2019humidit\u00e9 du sol peut \u00eatre mesur\u00e9 \u00e0 l\u2019aide d\u2019instruments intelligents qui vous informent des besoins en eau de votre plante. Id\u00e9al pour les amateurs de plantes qui veulent prendre soin de leurs plantes. Vous donnez de l\u2019eau en cas de besoin.<\/p>\n<\/div>\r\n                                            <\/div>\r\n                <\/li>\r\n                            <li class=\"accordion-row\">\r\n                    <a class=\"toggle\" href=#>\r\n                                                                            <h4 class=\"accordion-title\">Comment savoir combien d\u2019eau une plante a besoin?<\/h4>\r\n                                                <div class=\"switcher-icon\">\r\n                                                            <img decoding=\"async\" class=\"open-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/minus-regular.svg\" alt=\"\"\/>\r\n                                                                                        <img decoding=\"async\" class=\"close-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/plus-regular.svg\" alt=\"\"\/>\r\n                                                    <\/div>\r\n                    <\/a>\r\n                    <div class=\"inner\">\r\n                                                                            <div><p>Les plantes \u00e0 grandes feuilles consomment beaucoup plus d\u2019eau que les plantes \u00e0 feuilles plus fermes et plus \u00e9paisses (comme les plantes succulentes). En outre, la taille de la plante est importante. Un producteur professionnel est capable de calculer les besoins en eau d\u2019une plante, mais cela va probablement trop loin pour vous en tant qu\u2019amoureux individuel. Cependant, vous pouvez mesurer la teneur en humidit\u00e9 dans le sol avec le Plant Pulse capteur d\u2019humidit\u00e9 et l\u2019indicateur d\u2019humidit\u00e9 du sol pour savoir quand la plante a besoin d\u2019eau.<\/p>\n<\/div>\r\n                                            <\/div>\r\n                <\/li>\r\n                            <li class=\"accordion-row\">\r\n                    <a class=\"toggle\" href=#>\r\n                                                                            <h4 class=\"accordion-title\">En quelle saison se trouve la plante d\u2019int\u00e9rieur?<\/h4>\r\n                                                <div class=\"switcher-icon\">\r\n                                                            <img decoding=\"async\" class=\"open-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/minus-regular.svg\" alt=\"\"\/>\r\n                                                                                        <img decoding=\"async\" class=\"close-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/plus-regular.svg\" alt=\"\"\/>\r\n                                                    <\/div>\r\n                    <\/a>\r\n                    <div class=\"inner\">\r\n                                                                            <div><p>La saison joue \u00e9galement un r\u00f4le important dans la quantit\u00e9 d\u2019eau dont une plante d\u2019int\u00e9rieur a besoin. En hiver (dormant), les besoins en eau sont presque nuls. Mais pendant la saison de croissance, cela varie d\u2019une plante \u00e0 l\u2019autre. Certains aiment beaucoup d\u2019eau et d\u2019autres non. Avec le Plant Pulse capteur d\u2019humidit\u00e9, vous pouvez tr\u00e8s facilement r\u00e9gler les besoins en eau, voir aussi Plant Pulse capteur d\u2019humidit\u00e9.<\/p>\n<\/div>\r\n                                            <\/div>\r\n                <\/li>\r\n                            <li class=\"accordion-row\">\r\n                    <a class=\"toggle\" href=#>\r\n                                                                            <h4 class=\"accordion-title\">Quelle est la taille du pot ou du conteneur d\u2019une plante d\u2019int\u00e9rieur?<\/h4>\r\n                                                <div class=\"switcher-icon\">\r\n                                                            <img decoding=\"async\" class=\"open-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/minus-regular.svg\" alt=\"\"\/>\r\n                                                                                        <img decoding=\"async\" class=\"close-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/plus-regular.svg\" alt=\"\"\/>\r\n                                                    <\/div>\r\n                    <\/a>\r\n                    <div class=\"inner\">\r\n                                                                            <div><p>Par exemple, si vous avez un palmier de 2 m\u00e8tres dans un r\u00e9cipient de seulement 10 litres, il est juste de supposer que cette plante en pot se trouve dans un pot trop petit et qu\u2019il est n\u00e9cessaire de l\u2019arroser de mani\u00e8re continue. Si vous avez un grand r\u00e9cipient de 50 litres avec un bananier de 30 cm, vous n\u2019aurez presque jamais besoin de l\u2019arroser. Ainsi, la taille d\u2019une plante en pot par rapport \u00e0 la taille du pot joue \u00e9galement un r\u00f4le majeur. Le Plant Pulse capteur d\u2019humidit\u00e9 vous alertera imm\u00e9diatement ici si de l\u2019eau est n\u00e9cessaire, et notre humidim\u00e8tre de sol vous tiendra au courant des besoins en eau de vos plantes.<\/p>\n<\/div>\r\n                                            <\/div>\r\n                <\/li>\r\n                            <li class=\"accordion-row\">\r\n                    <a class=\"toggle\" href=#>\r\n                                                                            <h4 class=\"accordion-title\">Quel type de sol est utilis\u00e9 avec une plante en pot?<\/h4>\r\n                                                <div class=\"switcher-icon\">\r\n                                                            <img decoding=\"async\" class=\"open-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/minus-regular.svg\" alt=\"\"\/>\r\n                                                                                        <img decoding=\"async\" class=\"close-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/plus-regular.svg\" alt=\"\"\/>\r\n                                                    <\/div>\r\n                    <\/a>\r\n                    <div class=\"inner\">\r\n                                                                            <div><p>Le sol lui-m\u00eame est \u00e9galement tr\u00e8s important pour l\u2019arrosage des plantes, de vos plantes d\u2019int\u00e9rieur! Le sol peut-il retenir suffisamment d\u2019eau tout en restant a\u00e9r\u00e9? Ou bien votre plante est-elle dans un sol argileux qui rend l\u2019arrosage presque impossible? Ou est-ce un sol sableux, o\u00f9 l\u2019eau la traverse? Le sol doit bien absorber l\u2019eau et disposer d\u2019un bon tampon pour la nourriture. De plus, un excellent drainage est important pour \u00e9viter les eaux stagnantes et pr\u00e9venir la pourriture des racines. Un terreau bien a\u00e9r\u00e9 pour votre plante d\u2019int\u00e9rieur est d\u2019une grande importance. De nombreuses plantes d\u2019int\u00e9rieur restent trop longtemps dans le m\u00eame sol (parfois plusieurs ann\u00e9es) et sont souvent compl\u00e8tement lessiv\u00e9es.<\/p>\n<\/div>\r\n                                            <\/div>\r\n                <\/li>\r\n                            <li class=\"accordion-row\">\r\n                    <a class=\"toggle\" href=#>\r\n                                                                            <h4 class=\"accordion-title\">O\u00f9 se trouve la plante? Soleil ou ombre?<\/h4>\r\n                                                <div class=\"switcher-icon\">\r\n                                                            <img decoding=\"async\" class=\"open-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/minus-regular.svg\" alt=\"\"\/>\r\n                                                                                        <img decoding=\"async\" class=\"close-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/plus-regular.svg\" alt=\"\"\/>\r\n                                                    <\/div>\r\n                    <\/a>\r\n                    <div class=\"inner\">\r\n                                                                            <div><p>Il va sans dire qu\u2019une plante en pot consomme plus d\u2019eau au soleil qu\u2019\u00e0 l\u2019ombre. Il peut \u00eatre assez difficile de lui donner la bonne quantit\u00e9 d\u2019eau dans ces diff\u00e9rentes conditions. Pour cela, le Plant Pulse capteur d\u2019humidit\u00e9 et l\u2019humidim\u00e8tre de sol sont des outils de jardinage pratiques en les utilisant de mani\u00e8re permanente dans le pot. Ils vous informeront quand vous devriez les arroser.<\/p>\n<\/div>\r\n                                            <\/div>\r\n                <\/li>\r\n                            <li class=\"accordion-row\">\r\n                    <a class=\"toggle\" href=#>\r\n                                                                            <h4 class=\"accordion-title\">Quel est le niveau d\u2019humidit\u00e9?<\/h4>\r\n                                                <div class=\"switcher-icon\">\r\n                                                            <img decoding=\"async\" class=\"open-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/minus-regular.svg\" alt=\"\"\/>\r\n                                                                                        <img decoding=\"async\" class=\"close-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/plus-regular.svg\" alt=\"\"\/>\r\n                                                    <\/div>\r\n                    <\/a>\r\n                    <div class=\"inner\">\r\n                                                                            <div><p>Certaines plantes (par exemple les cactus) aiment l\u2019air sec, d\u2019autres (beaucoup de plantes tropicales) pr\u00e9f\u00e8rent un taux d\u2019humidit\u00e9 beaucoup plus \u00e9lev\u00e9. Bien s\u00fbr, plus d\u2019eau est consomm\u00e9e dans l\u2019air sec. Le Plant Pulse capteur d\u2019humidit\u00e9 et le moniteur d\u2019humidit\u00e9 sans fil mesureront les effets de l\u2019humidit\u00e9 sur le sol et indiqueront, par plante, si l\u2019arrosage est n\u00e9cessaire ou non.<\/p>\n<\/div>\r\n                                            <\/div>\r\n                <\/li>\r\n                            <li class=\"accordion-row\">\r\n                    <a class=\"toggle\" href=#>\r\n                                                                            <h4 class=\"accordion-title\">Quand dois-je arroser ma plante d\u2019int\u00e9rieur ou ma plante en pot?<\/h4>\r\n                                                <div class=\"switcher-icon\">\r\n                                                            <img decoding=\"async\" class=\"open-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/minus-regular.svg\" alt=\"\"\/>\r\n                                                                                        <img decoding=\"async\" class=\"close-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/plus-regular.svg\" alt=\"\"\/>\r\n                                                    <\/div>\r\n                    <\/a>\r\n                    <div class=\"inner\">\r\n                                                                            <div><p>Quand arroser les plantes? La r\u00e9ponse \u00e0 la question de savoir quand il faut donner de l\u2019eau aux plantes en pot, \u00e0 l\u2019int\u00e9rieur ou \u00e0 l\u2019ext\u00e9rieur, est g\u00e9n\u00e9ralement simple. Il est g\u00e9n\u00e9ralement conseill\u00e9 d\u2019arroser le matin, et que le moment est bien choisi, car il fait frais t\u00f4t dans la journ\u00e9e. Ceci s\u2019applique \u00e0 la fois au terreau et \u00e0 l\u2019eau. Si vous arrosez les plantes de terrasse avec de l\u2019eau du robinet froide en fin d\u2019apr\u00e8s-midi en \u00e9t\u00e9, le choc thermique sera le plus intense et de nombreuses plantes n\u2019aiment pas cela. Les agrumes, par exemple, auront des feuilles jaunes en quelques jours.<\/p>\n<\/div>\r\n                                            <\/div>\r\n                <\/li>\r\n                            <li class=\"accordion-row\">\r\n                    <a class=\"toggle\" href=#>\r\n                                                                            <h4 class=\"accordion-title\">Quel type d\u2019eau est-ce que je donne \u00e0 ma plante d\u2019int\u00e9rieur ou \u00e0 ma plante en pot?<\/h4>\r\n                                                <div class=\"switcher-icon\">\r\n                                                            <img decoding=\"async\" class=\"open-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/minus-regular.svg\" alt=\"\"\/>\r\n                                                                                        <img decoding=\"async\" class=\"close-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/plus-regular.svg\" alt=\"\"\/>\r\n                                                    <\/div>\r\n                    <\/a>\r\n                    <div class=\"inner\">\r\n                                                                            <div><p>L\u2019eau de pluie est certainement la meilleure eau \u00e0 donner \u00e0 vos plantes d\u2019int\u00e9rieur. Il contient \u00e0 peine des sels (CE = minimal \u00e0 pH bas), il doit donc \u00eatre fertilis\u00e9 r\u00e9guli\u00e8rement.<br \/>\nL\u2019eau du robinet ou l\u2019eau min\u00e9rale contient de nombreux min\u00e9raux (CE \u00e9lev\u00e9e \u00e0 0,8 mS \/ cm) et du calcium (pH \u00e9lev\u00e9 \u00e0 8), ce qui provoque un blocage rapide des plantes. Les bicarbonates jouent un r\u00f4le majeur ici. Il est donc conseill\u00e9 de m\u00e9langer l\u2019eau de pluie avec l\u2019eau du robinet.<\/p>\n<p>Le niveau de pH de l\u2019eau d\u2019irrigation peut \u00eatre mesur\u00e9 avec un pH-m\u00e8tre et la salinit\u00e9 totale de l\u2019eau avec un testteur EC que nous avons \u00e9galement dans notre catalogue.<\/p>\n<p>Les plantes d\u2019int\u00e9rieur ou en conteneur sont des plantes en pot, ce qui signifie qu\u2019elles sont dans un pot avec une quantit\u00e9 limit\u00e9e de sol. L\u2019eau qui est administr\u00e9e, y compris tous les sels, se retrouve directement dans le pot. La plante absorbe les sels (nutriments) dont elle a besoin sous forme de sels dissous, appel\u00e9s ions. L\u2019eau est la fa\u00e7on dont ces sels sont transport\u00e9s. S\u2019il y a beaucoup de sels non absorbables dans l\u2019eau que la plante n\u2019utilise pas, alors les sels restent dans le pot et s\u2019accumulent progressivement. Ceci est \u00e9galement appel\u00e9 la salinit\u00e9 qui est nocive pour la plante.<\/p>\n<\/div>\r\n                                            <\/div>\r\n                <\/li>\r\n                            <li class=\"accordion-row\">\r\n                    <a class=\"toggle\" href=#>\r\n                                                                            <h4 class=\"accordion-title\">Quelle temp\u00e9rature doit avoir l\u2019eau des plantes en pot?<\/h4>\r\n                                                <div class=\"switcher-icon\">\r\n                                                            <img decoding=\"async\" class=\"open-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/minus-regular.svg\" alt=\"\"\/>\r\n                                                                                        <img decoding=\"async\" class=\"close-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/plus-regular.svg\" alt=\"\"\/>\r\n                                                    <\/div>\r\n                    <\/a>\r\n                    <div class=\"inner\">\r\n                                                                            <div><p>La meilleure temp\u00e9rature est la temp\u00e9rature ambiante, c\u2019est la m\u00eame temp\u00e9rature que celle de la plante pour \u00e9viter les chocs thermiques. En \u00e9t\u00e9, nous pr\u00e9f\u00e9rons une douche froide, mais pas les plantes. Gardez le choc thermique aussi minime que possible. Les plantes tropicales et subtropicales sont les plus expos\u00e9es aux chocs thermiques. C\u2019est pourquoi ces plantes sont souvent dans une serre, afin d\u2019\u00e9viter autant que possible un changement de temp\u00e9rature.<\/p>\n<\/div>\r\n                                            <\/div>\r\n                <\/li>\r\n                            <li class=\"accordion-row\">\r\n                    <a class=\"toggle\" href=#>\r\n                                                                            <h4 class=\"accordion-title\">Comment puis-je arroser de grandes plantes en pot telles que des plantes de balcon et \/ ou de terrasse?<\/h4>\r\n                                                <div class=\"switcher-icon\">\r\n                                                            <img decoding=\"async\" class=\"open-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/minus-regular.svg\" alt=\"\"\/>\r\n                                                                                        <img decoding=\"async\" class=\"close-icon\" src=\"https:\/\/www.plantcaretools.com\/wp-content\/uploads\/2021\/09\/plus-regular.svg\" alt=\"\"\/>\r\n                                                    <\/div>\r\n                    <\/a>\r\n                    <div class=\"inner\">\r\n                                                                            <div><p>Comment puis-je arroser des plantes dans de grands conteneurs tels que des plantes de balcon et \/ ou de terrasse? Certaines plantes sont dans de grands pots et se retrouvent sur la terrasse au printemps, en plein soleil. Ainsi, beaucoup d\u2019eau est n\u00e9cessaire. Vous pouvez arroser abondamment le matin, pas trop vite bien s\u00fbr, jusqu\u2019\u00e0 ce que de l\u2019eau sorte du fond du pot. Cela \u00e9vacue \u00e9galement imm\u00e9diatement la salinit\u00e9, mais ne le faites pas trop intens\u00e9ment, car sinon, vous rincez le terreau riche. Assurez-vous \u00e9galement que la fertilisation est effectu\u00e9e correctement, car les engrais disparaissent \u00e9galement. La fr\u00e9quence d\u2019alimentation en eau de la plante d\u00e9pend beaucoup de la plante et des conditions.<\/p>\n<p>Avec un Plant Pulse capteur d\u2019humidit\u00e9 dans le pot de la plante, vous serez alert\u00e9 lorsque la plante aura soif. Cet outil de jardinage mesure la teneur en humidit\u00e9 du sol chaque seconde.<\/p>\n<p>Un moniteur d\u2019humidit\u00e9 sans fil mesure la teneur en humidit\u00e9 du sol de votre plante et indique si vous devez ou non l\u2019arroser.<\/p>\n<\/div>\r\n                                            <\/div>\r\n                <\/li>\r\n                    <\/ul>\r\n    <\/section>\r\n\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Arroser les plantes FAQ: mesurez l\u2019humidit\u00e9 du sol pour un entretien appropri\u00e9 Vous trouverez ici une liste de questions fr\u00e9quemment (FAQ) pos\u00e9es sur l\u2019arrosage des plantes \u2013 \u00e0 l\u2019int\u00e9rieur, en conteneurs ou autres plantes en pot. Mais aussi des informations sur l\u2019entretien de la pelouse et des plantes dans la cour ou le potager. Plantes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-10553","page","type-page","status-publish","hentry"],"blocksy_meta":{"page_title_panel":"","has_hero_section":"disabled","b0bcf61a477b44d34d3f466147a584bb":"","hero_section":"type-1","hero_elements":[{"id":"custom_title","enabled":false,"heading_tag":"h1","title":"Home","__id":"Y6khUB4gAGdZZFZBz_AR5"},{"id":"custom_description","enabled":false,"description_visibility":{"desktop":true,"tablet":true,"mobile":false},"__id":"Zx4PulaiwG6cVdABGw_Xi"},{"id":"custom_meta","enabled":false,"meta_elements":[{"id":"author","enabled":true,"label":"By","has_author_avatar":"yes","avatar_size":25},{"id":"post_date","enabled":true,"label":"On","date_format_source":"default","date_format":"M j, Y"},{"id":"comments","enabled":true}],"page_meta_elements":{"joined":true,"articles_count":true,"comments":true},"__id":"CaQRZzZbK6gV7jH42pGx-"},{"id":"breadcrumbs","enabled":false,"__id":"_B7WbyQ_9ZZQZlxQCAptJ"}],"6a86d140dec4159912641ae246b7801e":"","hero_alignment1":"left","hero_alignment2":"center","hero_vertical_alignment":"center","41aa13d1fed6ffecd364c2a39a774aca":"","hero_structure":"narrow","b340154c4a3bba02ca0c20ad330341b4":"","page_title_bg_type":"featured_image","custom_hero_background":{"attachment_id":null},"parallax":{"desktop":false,"tablet":false,"mobile":false},"44e6f3202a53661b006d1325e23c4ee4":"","hero_height":"250px","pageTitleFont":{"family":"Default","variation":"Default","size":{"desktop":"32px","tablet":"30px","mobile":"25px"},"line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"pageTitleFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageMetaFont":{"family":"Default","variation":"n6","size":"12px","line-height":"1.3","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"uppercase","text-decoration":"CT_CSS_SKIP_RULE"},"pageMetaFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageExcerptFont":{"family":"Default","variation":"Default","size":"CT_CSS_SKIP_RULE","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"CT_CSS_SKIP_RULE","text-decoration":"CT_CSS_SKIP_RULE"},"pageExcerptColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"breadcrumbsFont":{"family":"Default","variation":"n6","size":"12px","line-height":"CT_CSS_SKIP_RULE","letter-spacing":"CT_CSS_SKIP_RULE","text-transform":"uppercase","text-decoration":"CT_CSS_SKIP_RULE"},"breadcrumbsFontColor":{"default":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"initial":{"color":"CT_CSS_SKIP_RULEDEFAULT"},"hover":{"color":"CT_CSS_SKIP_RULEDEFAULT"}},"pageTitleOverlay":{"default":{"color":"CT_CSS_SKIP_RULE"}},"pageTitleBackground":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"no-repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"#EDEFF2"}}},"92d328a8166542dcbd3c70976a79e6fb":"","page_structure_type":"default","content_style":"inherit","vertical_spacing_source":"custom","content_area_spacing":"none","background":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"no-repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"CT_CSS_SKIP_RULE"}}},"content_background":{"background_type":"color","background_pattern":"type-1","background_image":{"attachment_id":null,"x":0,"y":0},"gradient":"linear-gradient(135deg,rgba(6,147,227,1) 0%,rgb(155,81,224) 100%)","background_repeat":"no-repeat","background_size":"auto","background_attachment":"scroll","patternColor":{"default":{"color":"#e5e7ea"}},"overlayColor":{"default":{"color":"CT_CSS_SKIP_RULE"}},"backgroundColor":{"default":{"color":"#ffffff"}}},"content_boxed_shadow":{"inherit":false,"blur":18,"spread":-6,"v_offset":12,"h_offset":0,"inset":false,"enable":true,"color":{"color":"rgba(34, 56, 101, 0.04)"}},"boxed_content_spacing":{"desktop":{"top":"40px","bottom":"40px","left":"40px","right":"40px","linked":true},"tablet":{"top":"35px","bottom":"35px","left":"35px","right":"35px","linked":true},"mobile":{"top":"20px","bottom":"20px","left":"20px","right":"20px","linked":true}},"content_boxed_radius":{"top":"3px","bottom":"3px","left":"3px","right":"3px","linked":true},"43724777f327b8931e8a2e0911cc6c52":"","disable_featured_image":"no","disable_header":"no","disable_footer":"no","3d43cf42515988c9004c52682b561440":"","d7604e7cb081bb659235ddc693d1da2d":"","hero_margin":{"desktop":"0","tablet":"0","mobile":"0","__changed":["mobile","tablet"]},"991a08045a14defff12390aff3a02d32":"","51a391c3170f49d078acc81826ddb351":"","9bcda35d13d6daea61cfad48e28d02e5":"","99b57b262e58f32660aaaa446b5f0b3c":"","95bdde3f5896f81b81883487140c520b":"","e020ebdedb0cb46b220928a4ebf7c0e5":"","47dd6dd73fcaac5d8363dd0a495159d6":"","873067bb6ab052f125371292b1ff7042":"","30620d1392afbd268c4c8dab82936123":"","a43688002e299611e44867a622ea70a0":"","4561e524d1adc49f2211bb560dc1cfc7":"","98a2f2fa0f1a02bdbc9f3b91cf2e4c06":"","1b8d0da3c48da055c34d7a83cdc91efa":"","36c76191ea6552ba5d7915c365e02ea4":"","bc8bd2f8f09309b34c7cd4d4f9b67717":"","0c7aa27137ffcdc65a77ce5f0c6e3928":"","8e89f5e8dfab363fe226a4e15c0bc4b4":"","f259a7341fc8f0f945501cdbb177bea7":"","183af9cd95f5720580abac239d1f1d05":"","ff343b6b7fa7f212f31373007485c729":"","96b44615bdbd5fecbcad729d98e17b18":"","fca6c23d3766460c5611872e7ad3cfa4":"","3d38b368984a097694aaed50e20dc609":"","d4e8a2923dcb3b4344d96aab244bf290":"","e471ebd3ea3fc7f242998a938c0fc7ac":"","c3bdf554de46a0788dbfd2d90ce4e6cf":"","ab1285c431759881cacea149314413d6":"","1453aad95c3f9f179cdc61c7a9ce2727":"","651a3fafeee39709b177fa7406c074eb":"","813f802b6b7d32878eefefe8a9b0683b":"","dd169c567080afe08a2a56a86ff6efaa":"","4916d94fa5100507f1f60356e0083290":"","04147a29052df8c47b6c3bd0a46ba2d7":"","19157a5a7240ed0911b475a44048671f":"","a96a589d95db7985a9b206cd4b4efeda":"","6759e28a5c7128fa70987f54aa92c0fe":"","ffdbb892ad159b98b3b9d7c299b39391":"","91c23c449a2c2aaeee79733479fd7959":"","pageTitlePadding":{"top":"50px","bottom":"50px","left":"auto","right":"auto","linked":true},"7bfe8e73eb9a38d5c47bedf28240f46b":"","9db0d72e6c7415998c4f2733821ab558":"","3f17dbdecf13ddba4d89b4476a374765":"","header_footer_scripts_panel":"","header_scripts":"","da78c8ee08ae13353f6666eacf95eb67":"","header_after_body_scripts":"","9655d8a4a01531b22f13ed7d1d8e6d47":"","footer_scripts":"","styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Arroser les Plantes FAQ - Plant Care Tools<\/title>\n<meta name=\"description\" content=\"Arroser les Plantes FAQ - Plant Care Tools est la webshop pour tous les instruments de mesure dans et autour de votre jardin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.plantcaretools.com\/fr\/arroser-les-plantes-faq\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.plantcaretools.com\\\/fr\\\/arroser-les-plantes-faq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.plantcaretools.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arroser les Plantes FAQ\"}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arroser les Plantes FAQ - Plant Care Tools","description":"Arroser les Plantes FAQ - Plant Care Tools est la webshop pour tous les instruments de mesure dans et autour de votre jardin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.plantcaretools.com\/fr\/arroser-les-plantes-faq\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.plantcaretools.com\/fr\/arroser-les-plantes-faq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.plantcaretools.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Arroser les Plantes FAQ"}]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.plantcaretools.com\/fr\/wp-json\/wp\/v2\/pages\/10553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.plantcaretools.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.plantcaretools.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.plantcaretools.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.plantcaretools.com\/fr\/wp-json\/wp\/v2\/comments?post=10553"}],"version-history":[{"count":6,"href":"https:\/\/www.plantcaretools.com\/fr\/wp-json\/wp\/v2\/pages\/10553\/revisions"}],"predecessor-version":[{"id":23270,"href":"https:\/\/www.plantcaretools.com\/fr\/wp-json\/wp\/v2\/pages\/10553\/revisions\/23270"}],"wp:attachment":[{"href":"https:\/\/www.plantcaretools.com\/fr\/wp-json\/wp\/v2\/media?parent=10553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}